{"id":54675,"date":"2024-01-09T13:33:06","date_gmt":"2024-01-09T05:33:06","guid":{"rendered":"https:\/\/metalstek.com\/metaux-refractaires\/tantale-ta\/creuset-de-tantale\/"},"modified":"2025-05-06T15:12:24","modified_gmt":"2025-05-06T07:12:24","slug":"creuset-de-tantale","status":"publish","type":"page","link":"https:\/\/metalstek.com\/fr\/metaux-refractaires\/tantale-ta\/creuset-de-tantale\/","title":{"rendered":"Creuset de tantale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"54675\" class=\"elementor elementor-54675 elementor-10343\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d7126c e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-parent\" data-id=\"9d7126c\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a67dd6a e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"a67dd6a\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d8c8fc elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-template\" data-id=\"1d8c8fc\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"2018\" class=\"elementor elementor-2018\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-566b6908 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-parent\" data-id=\"566b6908\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/metalstek.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1\\u670810\\u65e5-2.mp4&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container elementor-hidden-phone\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted elementor-html5-video\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div><div class=\"elementor-element elementor-element-20228167 e-con-full e-flex elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"20228167\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aad3bb8 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"5aad3bb8\" data-element_type=\"widget\" id=\"bannerTitle\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Creuset de tantale<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75fd0533 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"75fd0533\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/metalstek.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-woocommerce.min.css\"><nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\">Accueil<\/nav>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8ae5d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"4c8ae5d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Creusets en tantale pour applications \u00e0 haute temp\u00e9rature<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2107da e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"a2107da\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ff3fa06 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"ff3fa06\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-69a9ec6 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"69a9ec6\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7da72b1 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"7da72b1\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d901c27 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"d901c27\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ba56fa8 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"ba56fa8\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca41d16 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"ca41d16\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b66be7 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"3b66be7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Creuset pour faisceau d'\u00e9lectrons en tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf81070 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"bf81070\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e504dfb e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"e504dfb\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a43975f external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"a43975f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"479\" height=\"479\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239.webp\" class=\"attachment-large size-large wp-image-36995\" alt=\"tantalum-crucible1-jpg\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239.webp 479w, https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239-300x300.webp 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239-150x150.webp 150w, https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239-100x100.webp 100w, https:\/\/metalstek.com\/wp-content\/uploads\/2023\/12\/Tantalum-Crucible1.jpg-e1714039457239-68x68.webp 68w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ad8883 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"5ad8883\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c81aba6 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"c81aba6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Mat\u00e9riau : Tantale ou alliages de tantale<\/p><p>Grade : R05200, R05400, R05252 (Ta-2.5W), R05255 (Ta-10W), R05240 (Ta-40Nb)<\/p><p>Puret\u00e9 : &gt;99,9%<\/p><p>Norme : ASTM B708<\/p><p>Surface : Polie, Finition Tournage<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-929e940 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"929e940\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-060cc4b singlexunpan elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-button\" data-id=\"060cc4b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un devis<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e7d65d e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"3e7d65d\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efebd0d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"efebd0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Creuset standard en tantale (cylindrique)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcb03cd e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"bcb03cd\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e6304d6 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"e6304d6\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c120ee external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"2c120ee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"324\" height=\"276\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/01\/Tantalum-Crucible.jpg\" class=\"attachment-large size-large wp-image-39119\" alt=\"tantalum-crucible\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/01\/Tantalum-Crucible.jpg 324w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/01\/Tantalum-Crucible-300x256.jpg 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/01\/Tantalum-Crucible-64x55.jpg 64w\" sizes=\"(max-width: 324px) 100vw, 324px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6695af e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"b6695af\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23065d7 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"23065d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Mat\u00e9riau : Tantale ou alliages de tantale<\/p><p>Qualit\u00e9 : Ta&gt;99.9%, R05200, R05400, R05252 (Ta-2.5W), R05255 (Ta-10W), R05240 (Ta-40Nb)<\/p><p>Couvercle : Avec ou sans<\/p><p>Norme : ASTM B708<\/p><p>Surface : Polie, Finition Tournage<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70bcb3c e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"70bcb3c\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95cdb58 singlexunpan elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-button\" data-id=\"95cdb58\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un devis<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2567a00 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"2567a00\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>MetalsTek Engineering propose des creusets en tantale, y compris des creusets \u00e0 embouchure ronde, des creusets coniques, des creusets elliptiques et des creusets sans fond, pour diverses applications. Ces creusets sont con\u00e7us pour r\u00e9sister \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es et \u00e0 des environnements corrosifs, ce qui les rend adapt\u00e9s \u00e0 la m\u00e9tallurgie, \u00e0 la fusion des terres rares, \u00e0 la production de silicium monocristallin, \u00e0 l&#8217;\u00e9nergie solaire, aux cristaux artificiels et aux industries de traitement m\u00e9canique. Des options de personnalisation sont disponibles en fonction des sp\u00e9cifications et des exigences du client.  <\/p><p>Avec plus d&#8217;une d\u00e9cennie d&#8217;exp\u00e9rience dans l&#8217;industrie, MetalsTek peut vous aider \u00e0 gagner du temps et \u00e0 r\u00e9duire vos co\u00fbts gr\u00e2ce \u00e0 des creusets en tantale de qualit\u00e9 et rentables.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43b6887 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"43b6887\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-558cae1 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"558cae1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sp\u00e9cifications du creuset en tantale<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd1a4ee elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding e-con e-child\" data-id=\"fd1a4ee\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3ef8805 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding e-con e-child\" data-id=\"3ef8805\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c416b80 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"c416b80\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50171b5 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"50171b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Creuset E-Beam  <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d81a909 external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"d81a909\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"448\" height=\"443\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/04\/Crucibles.svg\" class=\"attachment-full size-full wp-image-45363\" alt=\"crucibles\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-135b053 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"135b053\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-456f611 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"456f611\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Creuset cylindrique<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-081830b external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"081830b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"386\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/04\/Cylinderical-Tungsten-Crucible-3.png\" class=\"attachment-woocommerce_single size-woocommerce_single wp-image-45367\" alt=\"cylinderical-tungsten-crucible-3\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/04\/Cylinderical-Tungsten-Crucible-3.png 579w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/04\/Cylinderical-Tungsten-Crucible-3-300x200.png 300w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a16d9f elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-shortcode\" data-id=\"7a16d9f\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><h2 id=\"tablepress-299-name\" class=\"tablepress-table-name tablepress-table-name-id-299\">Tantalum  E-Beam Crucibles<\/h2>\n\n<table id=\"tablepress-299\" class=\"tablepress tablepress-id-299\" aria-labelledby=\"tablepress-299-name\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Item No.<\/th><th class=\"column-2\">Capacities (mL)<\/th><th class=\"column-3\">Top Diameter A (mm\/inch)<\/th><th class=\"column-4\">Height B (mm\/inch)<\/th><th class=\"column-5\">Wall Thickness C (mm\/inch)<\/th><th class=\"column-6\">Inquiry<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">ECTA-04<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">22.5 (0.89\")<\/td><td class=\"column-4\">15.1 (0.60\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-04')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">ECTA-04A<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">21.5 (0.85\")<\/td><td class=\"column-4\">17.5 (0.69\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-04A')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">ECTA-07<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">28.6 (1.13\")<\/td><td class=\"column-4\">13.2 (0.52\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-07')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">ECTA-07A<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">29.6 (1.17\")<\/td><td class=\"column-4\">14.3 (0.56\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-07A')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">ECTA-12<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">33.9 (1.33\")<\/td><td class=\"column-4\">19.5 (0.77\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-12')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">ECTA-12A<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">34.3 (1.35\")<\/td><td class=\"column-4\">17.3 (0.68\")<\/td><td class=\"column-5\">3.2 (0.13\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-12A')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">ECTA-15<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">37.6 (1.48\")<\/td><td class=\"column-4\">17.0 (0.67\")<\/td><td class=\"column-5\">3.2 (0.13\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-15')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">ECTA-20<\/td><td class=\"column-2\">20<\/td><td class=\"column-3\">42.5 (1.67\")<\/td><td class=\"column-4\">19.5 (0.77\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-20')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">ECTA-25<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">47.0 (1.85\")<\/td><td class=\"column-4\">17.3 (0.68\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-25')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">ECTA-25A<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">41.5 (1.63\")<\/td><td class=\"column-4\">23.9 (0.94\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-25A')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">ECTA-35<\/td><td class=\"column-2\">35<\/td><td class=\"column-3\">52.9 (2.08\")<\/td><td class=\"column-4\">19.5 (0.77\")<\/td><td class=\"column-5\">2.4 (0.09\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-35')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">ECTA-40<\/td><td class=\"column-2\">40<\/td><td class=\"column-3\">51.6 (2.03\")<\/td><td class=\"column-4\">25.9 (1.02\")<\/td><td class=\"column-5\">3.2 (0.13\")<\/td><td class=\"column-6\"><a href=\"#submitQuote\" style=\"color:white\"><button style=\"background:#3b6faa;border:none;font-size:14px;width:100px;height:30px\" onclick=\"fillForm('ECTA-40')\">Get A Quote<\/button><\/a><\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td colspan=\"6\" class=\"column-1\">Tantalum E-Beam Crucible material, shape and size can be customized per requests. <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0d88d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-shortcode\" data-id=\"3f0d88d\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><h2 id=\"tablepress-116-name\" class=\"tablepress-table-name tablepress-table-name-id-116\">Standard Tantalum Crucibles<\/h2>\n\n<table id=\"tablepress-116\" class=\"tablepress tablepress-id-116\" aria-labelledby=\"tablepress-116-name\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\"><strong><strong>ITEM NO.<\/strong><\/strong><\/th><th class=\"column-2\"><strong><strong>CAPACITY<\/strong><\/strong><\/th><th class=\"column-3\"><strong><strong>OD<\/strong><\/strong><\/th><th class=\"column-4\"><strong><strong>ID<\/strong><\/strong><\/th><th class=\"column-5\"><strong><strong>DEPTH<\/strong><\/strong><\/th><th class=\"column-6\"><strong><strong>Tolerances<\/strong><\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><strong><strong>(mL)<\/strong><\/strong><\/td><td class=\"column-3\"><strong><strong>(mm)<\/strong><\/strong><\/td><td class=\"column-4\"><strong><strong>(mm)<\/strong><\/strong><\/td><td class=\"column-5\"><strong><strong>\uff08<\/strong><strong>mm<\/strong><strong>\uff09<\/strong><\/strong><\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">TAC-891000<\/td><td class=\"column-2\">1000<\/td><td class=\"column-3\">127<\/td><td class=\"column-4\">125.5<\/td><td class=\"column-5\">89<\/td><td class=\"column-6\">OD: \u00b110 %<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">TAC-450100<\/td><td class=\"column-2\">100<\/td><td class=\"column-3\">59<\/td><td class=\"column-4\">58<\/td><td class=\"column-5\">45<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">TAC-410075<\/td><td class=\"column-2\">75<\/td><td class=\"column-3\">51<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\">ID: \u00b110 %<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">TAC-410055<\/td><td class=\"column-2\">55<\/td><td class=\"column-3\">47<\/td><td class=\"column-4\">46<\/td><td class=\"column-5\">41<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">TAC-340045<\/td><td class=\"column-2\">45<\/td><td class=\"column-3\">46<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">34<\/td><td class=\"column-6\">DPT: \u00b110 %<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">TAC-290035<\/td><td class=\"column-2\">35<\/td><td class=\"column-3\">46<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">29<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">TAC-220025<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">45<\/td><td class=\"column-4\">44<\/td><td class=\"column-5\">22<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">TAC-290020<\/td><td class=\"column-2\">20<\/td><td class=\"column-3\">33<\/td><td class=\"column-4\">32<\/td><td class=\"column-5\">29<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">TAC-220015<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">33<\/td><td class=\"column-4\">32<\/td><td class=\"column-5\">22<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">TAC-220010<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">27<\/td><td class=\"column-4\">26<\/td><td class=\"column-5\">22<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">TAC-180005<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">21<\/td><td class=\"column-4\">20<\/td><td class=\"column-5\">18<\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td colspan=\"6\" class=\"column-1\">Tantalum Crucible material, shape and size can be customized per requests. <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5df2c elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-shortcode\" data-id=\"2b5df2c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><h2 id=\"tablepress-117-name\" class=\"tablepress-table-name tablepress-table-name-id-117\">Straight-Wall Tantalum Crucibles Specifications<\/h2>\n\n<table id=\"tablepress-117\" class=\"tablepress tablepress-id-117\" aria-labelledby=\"tablepress-117-name\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\"><strong><strong>Diameter<\/strong><\/strong><\/th><th class=\"column-2\"><strong><strong>Thickness<\/strong><\/strong><\/th><th class=\"column-3\"><strong><strong>Height<\/strong><\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\"><strong><strong>(mm)\u00a0\u00a0<\/strong><\/strong><\/td><td class=\"column-2\"><strong><strong>(mm) \u00a0\u00a0<\/strong><\/strong><\/td><td class=\"column-3\"><strong><strong>(mm)<\/strong><\/strong><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">30 ~ 50<\/td><td class=\"column-2\">2 ~ 10<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">50 ~ 100<\/td><td class=\"column-2\">3 ~ 15<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">100 ~ 150<\/td><td class=\"column-2\">3 ~ 15<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">150 ~ 200<\/td><td class=\"column-2\">5 ~ 20<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">200 ~ 300<\/td><td class=\"column-2\">8 ~ 20<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">300 ~ 400<\/td><td class=\"column-2\">8 ~ 30<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">400 ~ 450<\/td><td class=\"column-2\">8 ~ 30<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">450 ~ 500<\/td><td class=\"column-2\">8 ~ 30<\/td><td class=\"column-3\">30 ~ 500<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b2babe elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"9b2babe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Applications du creuset en tantale<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b91a878 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"b91a878\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale trouvent des applications dans diverses industries en raison de leurs propri\u00e9t\u00e9s de r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es et \u00e0 la corrosion. Parmi les applications notables, on peut citer <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9679876 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-icon-list\" data-id=\"9679876\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/metalstek.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>1. Industrie m\u00e9tallurgique : <\/strong>Les creusets de tantale sont utilis\u00e9s dans les processus m\u00e9tallurgiques pour produire divers m\u00e9taux et alliages.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>2. Industrie des terres rares:<\/strong>Les creusets en tantale jouent un r\u00f4le dans l'industrie des terres rares, en particulier dans les processus li\u00e9s aux \u00e9l\u00e9ments des terres rares.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>3. production de silicium monocristallin : <\/strong>Les creusets sont utilis\u00e9s dans la production de silicium monocristallin, un mat\u00e9riau cl\u00e9 dans l'industrie \u00e9lectronique.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> <strong>4. \u00e9nergie solaire::<\/strong>Les creusets en tantale contribuent aux applications dans le domaine de l'\u00e9nergie solaire, potentiellement dans la fabrication de cellules solaires ou de composants connexes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>5. Cristaux artificiels : <\/strong>Ils sont utilis\u00e9s dans la production de cristaux artificiels pour diverses applications, y compris l'\u00e9lectronique et l'optique.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>6. Industries de transformation m\u00e9canique : <\/strong>Les creusets en tantale sont utilis\u00e9s dans diverses applications de traitement m\u00e9canique, o\u00f9 leur r\u00e9sistance aux temp\u00e9ratures \u00e9lev\u00e9es est b\u00e9n\u00e9fique.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e37a46 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"1e37a46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les applications sp\u00e9cifiques peuvent varier en fonction des exigences de l&#8217;industrie et de la personnalisation des creusets pour r\u00e9pondre \u00e0 ces besoins.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d0b48 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"33d0b48\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Emballage<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbcaca9 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"fbcaca9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5456802 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"5456802\" data-element_type=\"container\" data-settings=\"{\"content_width\":\"full\",\"ang_container_spacing_size\":\"default_padding\"}\"><div class=\"elementor-element elementor-element-ff8b9d2 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"ff8b9d2\" data-element_type=\"container\" data-settings=\"{\"content_width\":\"boxed\",\"ang_container_spacing_size\":\"default_padding\"}\"><div class=\"e-con-inner\"><div class=\"elementor-element elementor-element-b3008c3 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"b3008c3\" data-element_type=\"container\" data-settings=\"{\"content_width\":\"boxed\",\"ang_container_spacing_size\":\"default_padding\"}\"><div class=\"e-con-inner\"><div class=\"elementor-element elementor-element-082ba68 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"082ba68\" data-element_type=\"container\" data-settings=\"{\"content_width\":\"full\",\"ang_container_spacing_size\":\"default_padding\"}\"><div class=\"elementor-element elementor-element-2ddc8d1 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"2ddc8d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Nos creusets de tantale sont clairement \u00e9tiquet\u00e9s et marqu\u00e9s \u00e0 l&#8217;ext\u00e9rieur pour garantir une identification et un contr\u00f4le de qualit\u00e9 efficaces. Nous prenons grand soin d&#8217;\u00e9viter tout dommage qui pourrait \u00eatre caus\u00e9 pendant le stockage ou le transport. <\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b70902 e-con-full e-flex elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"9b70902\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d850b elementor-widget__width-auto e-transform e-transform elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-template\" data-id=\"d8d850b\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"601\" class=\"elementor elementor-601\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25f40b9a e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover quote e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"25f40b9a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f1fc9c6 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"7f1fc9c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Request A Quote<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56d31d96 elementor-button-align-center submitQuote elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-global elementor-global-584 elementor-widget-form\" data-id=\"56d31d96\" data-element_type=\"widget\" id=\"submitQuote\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width_tablet&quot;:&quot;100&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.20.0 - 11-03-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"Contact Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"601\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"56d31d96\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Name*\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-md-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Email*\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_f2cdd3f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f2cdd3f\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCompany\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_f2cdd3f]\" id=\"form-field-field_f2cdd3f\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Company\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-Country elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-Country\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCountry\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[Country]\" id=\"form-field-Country\" class=\"elementor-field-textual elementor-size-md\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"United States\">United States<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Argentina\">Argentina<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Australia\">Australia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Austria\">Austria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Belgium\">Belgium<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Brazil\">Brazil<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bulgaria\">Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Canada\">Canada<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chile\">Chile<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"China\">China<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Colombia\">Colombia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Croatia\">Croatia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Czech Republic\">Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Denmark\">Denmark<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Egypt\">Egypt<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Estonia\">Estonia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Finland\">Finland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"France\">France<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Germany\">Germany<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Greece\">Greece<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Hong Kong\">Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Hungary\">Hungary<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Iceland\">Iceland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"India\">India<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Indonesia\">Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ireland\">Ireland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Israel\">Israel<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Italy\">Italy<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Japan\">Japan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Latvia\">Latvia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Lithuania\">Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Luxembourg\">Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Malaysia\">Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Mexico\">Mexico<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Netherlands\">Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"New Zealand\">New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Norway\">Norway<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Peru\">Peru<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Philippines\">Philippines<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Poland\">Poland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Portugal\">Portugal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Romania\">Romania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Saudi Arabia\">Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Singapore\">Singapore<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Slovakia\">Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Slovenia\">Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"South Africa\">South Africa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"South Korea\">South Korea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Spain\">Spain<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Sweden\">Sweden<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Switzerland\">Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Taiwan\">Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Thailand\">Thailand<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Turkey\">Turkey<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"United Arab Emirates\">United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"United Kingdom\">United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Vietnam\">Vietnam<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-Product elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-Product\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tProduct\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[Product]\" id=\"form-field-Product\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Product\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_ccb465f elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_ccb465f\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tQuantity\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_ccb465f]\" id=\"form-field-field_ccb465f\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Quantity*\" required=\"required\" aria-required=\"true\" min=\"1\" max=\"1000000\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-comments elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-comments\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tComments*\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[comments]\" id=\"form-field-comments\" rows=\"4\" placeholder=\"Comments* If you know, please let us know the product name, dimensions, quantity or attach a drawing below...\" required=\"required\" aria-required=\"true\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_e652432 elementor-col-100\">\n\t\t\t\t\t<div style=\"color:#313766\">Attach a Drawing<\/div>\n<div><\/div>\n<label class=\"custom-upload-btn\">\n\n  Choose A File\n <input type=\"file\" onchange=\"showFileName(this)\"  name=\"form_fields[cusupload][]\" id=\"form-field-cusupload\" class=\"elementor-field elementor-size-md  elementor-upload-field\" multiple=\"multiple\" data-maxsize=\"5\" data-maxsize-message=\"This file exceeds the maximum allowed size 5Mb.\">\n<\/label>\n<span style=\"color:#313766;\" class=\"file-name\" id=\"file-name\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-cusupload elementor-col-100\">\n\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[cusupload][]\" id=\"form-field-cusupload\" class=\"elementor-field elementor-size-md  elementor-upload-field\" multiple=\"multiple\" data-maxsize=\"5\" data-maxsize-message=\"This file exceeds the maximum allowed size.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_3d27c27 elementor-col-100\">\n\t\t\t\t\t<span style=\"color:lightgray;font-size:14px\">*Company e-mail address is preferred.\u00a0<\/span>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_5ad5445 elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_5ad5445\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LdSb50pAAAAAF7-ZRd9hRqhOeGV8x2CBjBhF4nm\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons elementor-md-100\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-md\" id=\"submitbtn\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GET A QUOTE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18e88ae7 e-con-full e-flex elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-parent\" data-id=\"18e88ae7\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-31bc3a93 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"31bc3a93\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2886ffc3 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"2886ffc3\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-29aa4b42 post e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"29aa4b42\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4dcc62c5 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"4dcc62c5\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-652867b5 Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"652867b5\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-19c533cc e-flex e-con-boxed elementor-repeater-item-default_padding sk-none elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"19c533cc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55d5dc3 elementor-widget-divider--view-line elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-divider\" data-id=\"55d5dc3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23c85d75 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"23c85d75\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Guide complet des propri\u00e9t\u00e9s et des applications du creuset en tantale : Tout ce qu'il faut savoir<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79de6566 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"79de6566\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale ne sont peut-\u00eatre pas la premi\u00e8re chose qui vient \u00e0 l&#8217;esprit lorsqu&#8217;on parle de technologie de pointe, mais leur r\u00f4le dans l&#8217;a\u00e9rospatiale, les semi-conducteurs et la fabrication de pointe est vital. Ces creusets robustes peuvent r\u00e9sister \u00e0 des temp\u00e9ratures extr\u00eames et \u00e0 des environnements corrosifs qui d\u00e9truiraient la plupart des mat\u00e9riaux. \u00cates-vous curieux de savoir comment un si petit composant peut avoir un impact massif ? Dans cet article, nous examinerons les propri\u00e9t\u00e9s fascinantes, les applications surprenantes et les raisons pour lesquelles les creusets en tantale sont indispensables \u00e0 certains des processus les plus exigeants au monde.   <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72dc70d e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"72dc70d\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-679948a9 tbcontent elementor-widget__width-initial elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-table-of-contents\" data-id=\"679948a9\" data-element_type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h4&quot;],&quot;exclude_headings_by_selector&quot;:&quot;#bannerTitle&quot;,&quot;container&quot;:&quot;.Chapter&quot;,&quot;collapse_subitems&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;marker_view&quot;:&quot;numbers&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.20.0 - 11-03-2024 *\/\n.elementor-widget-table-of-contents .elementor-toc__header-title{color:var(--header-color)}.elementor-widget-table-of-contents.elementor-toc--collapsed .elementor-toc__toggle-button--collapse,.elementor-widget-table-of-contents:not(.elementor-toc--collapsed) .elementor-toc__toggle-button--expand{display:none}.elementor-widget-table-of-contents .elementor-widget-container{min-height:var(--box-min-height);border:var(--box-border-width,1px) solid var(--box-border-color,#9da5ae);border-radius:var(--box-border-radius,3px);background-color:var(--box-background-color);transition:min-height .4s;overflow:hidden}.elementor-toc__header{display:flex;align-items:center;justify-content:space-between;padding:var(--box-padding,20px);background-color:var(--header-background-color);border-bottom:var(--separator-width,1px) solid var(--box-border-color,#9da5ae)}.elementor-toc__header-title{font-size:18px;margin:0;color:var(--header-color);flex-grow:1}.elementor-toc__toggle-button{cursor:pointer;display:inline-flex}.elementor-toc__toggle-button i{color:var(--toggle-button-color)}.elementor-toc__toggle-button svg{height:1em;width:1em;fill:var(--toggle-button-color)}.elementor-toc__spinner-container{text-align:center}.elementor-toc__spinner{font-size:2em}.elementor-toc__spinner.e-font-icon-svg{height:1em;width:1em}.elementor-toc__body{padding:var(--box-padding,20px);max-height:var(--toc-body-max-height);overflow-y:auto}.elementor-toc__body::-webkit-scrollbar{width:7px}.elementor-toc__body::-webkit-scrollbar-thumb{background-color:#babfc5;border-radius:10px}.elementor-toc__list-wrapper{list-style:none;padding:0}.elementor-toc__list-item{margin-bottom:.5em}.elementor-toc__list-item.elementor-item-active{font-weight:700}.elementor-toc__list-item .elementor-toc__list-wrapper{margin-top:.5em;margin-left:var(--nested-list-indent,1em)}.elementor-toc__list-item-text{transition-duration:var(--item-text-transition-duration)}.elementor-toc__list-item-text:hover{color:var(--item-text-hover-color);-webkit-text-decoration:var(--item-text-hover-decoration);text-decoration:var(--item-text-hover-decoration)}.elementor-toc__list-item-text.elementor-item-active{color:var(--item-text-active-color);-webkit-text-decoration:var(--item-text-active-decoration);text-decoration:var(--item-text-active-decoration)}.elementor-toc__list-item-text-wrapper{display:flex;align-items:center}.elementor-toc__list-item-text-wrapper:before,.elementor-toc__list-item-text-wrapper i{margin-right:8px;color:var(--marker-color)}.elementor-toc__list-item-text-wrapper svg{margin-right:8px;fill:var(--marker-color);height:var(--marker-size,.5em);width:var(--marker-size,.5em)}.elementor-toc__list-item-text-wrapper i{font-size:var(--marker-size,.5em)}.elementor-toc__list-item-text-wrapper:before{font-size:var(--marker-size,1em)}.elementor-toc--content-ellipsis .elementor-toc__list-item-text{white-space:nowrap;overflow:hidden;text-overflow:ellipsis}.elementor-toc__list-items--collapsible>.elementor-toc__list-wrapper>.elementor-toc__list-item>.elementor-toc__list-wrapper{display:none}.elementor-toc__heading-anchor{position:absolute}.elementor-toc__body .elementor-toc__list-item-text{color:var(--item-text-color);-webkit-text-decoration:var(--item-text-decoration);text-decoration:var(--item-text-decoration);transition-duration:var(--item-text-transition-duration)}.elementor-toc__body .elementor-toc__list-item-text:hover{color:var(--item-text-hover-color);-webkit-text-decoration:var(--item-text-hover-decoration);text-decoration:var(--item-text-hover-decoration)}.elementor-toc__body .elementor-toc__list-item-text.elementor-item-active{color:var(--item-text-active-color);-webkit-text-decoration:var(--item-text-active-decoration);text-decoration:var(--item-text-active-decoration)}ol.elementor-toc__list-wrapper{counter-reset:item}ol.elementor-toc__list-wrapper .elementor-toc__list-item{counter-increment:item}ol.elementor-toc__list-wrapper .elementor-toc__list-item-text-wrapper:before{content:counters(item,\".\") \". \"}<\/style>\t\t<div class=\"elementor-toc__header\">\n\t\t\t<h3 class=\"elementor-toc__header-title\">\n\t\t\t\tTable des mati\u00e8res\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t<div id=\"elementor-toc__679948a9\" class=\"elementor-toc__body elementor-toc__list-items--collapsible\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c824bc4 Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"7c824bc4\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d635478 e-flex e-con-boxed elementor-repeater-item-default_padding sk-none elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"d635478\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f441766 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"6f441766\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 1<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e1d992c e-con-full e-transform e-flex elementor-repeater-item-default_padding sk-none elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"7e1d992c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57b39c0b elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"57b39c0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce qu'un creuset en tantale ?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0626b3 external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"d0626b3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"532\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Features_Applications_of_Tungsten_Crucibles-jpg.webp\" class=\"attachment-full size-full wp-image-48035\" alt=\"features_applications_of_tungsten_crucibles-jpg\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Features_Applications_of_Tungsten_Crucibles-jpg.webp 822w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Features_Applications_of_Tungsten_Crucibles-300x194.webp 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Features_Applications_of_Tungsten_Crucibles-768x497.webp 768w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Features_Applications_of_Tungsten_Crucibles-600x388.webp 600w\" sizes=\"(max-width: 822px) 100vw, 822px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b42f7d2 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"2b42f7d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Un creuset en tantale est un r\u00e9cipient sp\u00e9cialis\u00e9 fabriqu\u00e9 \u00e0 partir d&#8217;un m\u00e9tal rare et r\u00e9sistant \u00e0 la corrosion. Les creusets en tantale sont principalement utilis\u00e9s dans des applications \u00e0 haute temp\u00e9rature, notamment en m\u00e9tallurgie et en science des mat\u00e9riaux. Leur fonction principale est de contenir des mat\u00e9riaux qui doivent \u00eatre fondus ou trait\u00e9s \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es. Les propri\u00e9t\u00e9s du tantale, notamment son point de fusion \u00e9lev\u00e9 d&#8217;environ 3 000 \u00b0C (5 432 \u00b0F) et son excellente r\u00e9sistance aux attaques chimiques, rendent les creusets en tantale essentiels pour ces applications.   <\/p><p>Les caract\u00e9ristiques uniques du tantale le distinguent des autres m\u00e9taux. Les creusets en tantale de haute puret\u00e9, qui peuvent atteindre un niveau de puret\u00e9 de 99,95 %, sont souvent utilis\u00e9s dans des environnements o\u00f9 la contamination pourrait compromettre les r\u00e9sultats souhait\u00e9s. Par exemple, dans l&#8217;industrie des semi-conducteurs, o\u00f9 les impuret\u00e9s, m\u00eame \u00e0 l&#8217;\u00e9tat de traces, peuvent ruiner les processus, ces creusets en tantale sur mesure fournissent l&#8217;assurance n\u00e9cessaire de puret\u00e9 et de fiabilit\u00e9. En outre, en raison de la n\u00e9cessit\u00e9 d&#8217;une gestion thermique pr\u00e9cise, les creusets en tantale sans soudure destin\u00e9s aux laboratoires sont particuli\u00e8rement appr\u00e9ci\u00e9s, car ils minimisent les gradients thermiques et garantissent un chauffage uniforme.   <\/p><p>Outre leur utilisation en m\u00e9tallurgie, les creusets en tantale ont plusieurs applications dans le domaine en plein essor des nanotechnologies, car ils peuvent r\u00e9sister aux conditions extr\u00eames requises pour la synth\u00e8se de nouveaux mat\u00e9riaux. Les creusets en tantale pour faisceau d&#8217;\u00e9lectrons sont con\u00e7us explicitement pour la fusion par faisceau d&#8217;\u00e9lectrons, ce qui permet de produire des mat\u00e9riaux de haute qualit\u00e9 dans des conditions contr\u00f4l\u00e9es. En outre, leur r\u00e9sistance \u00e0 la corrosion permet d&#8217;utiliser les creusets en tantale dans des environnements chimiques o\u00f9 les mat\u00e9riaux traditionnels seraient d\u00e9faillants.  <\/p><p>En r\u00e9sum\u00e9, les creusets en tantale sont indispensables dans divers processus \u00e0 haute temp\u00e9rature dans de nombreuses industries. Leurs propri\u00e9t\u00e9s uniques leur permettent de fonctionner efficacement dans des conditions exigeantes, ce qui en fait un choix privil\u00e9gi\u00e9 pour les chercheurs et les fabricants. Pour ceux qui cherchent \u00e0 se procurer des creusets en tantale, il existe des options d&#8217;achat de creusets en tantale en ligne qui r\u00e9pondent \u00e0 diverses sp\u00e9cifications, garantissant l&#8217;accessibilit\u00e9 de ces outils essentiels.  <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ea5e4a1 Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"3ea5e4a1\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-37a8b706 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"37a8b706\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18286e34 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"18286e34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 2<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fabd428 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"7fabd428\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f02d432 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"4f02d432\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce qui fait la sp\u00e9cificit\u00e9 du tantale - Propri\u00e9t\u00e9s du tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a737b45 external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"6a737b45\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum.webp\" class=\"attachment-full size-full wp-image-48191\" alt=\"properties-element-tantalum\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum.webp 600w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum-300x300.webp 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum-150x150.webp 150w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum-100x100.webp 100w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/08\/properties-element-Tantalum-68x68.webp 68w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f50708 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"21f50708\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le tantale est un \u00e9l\u00e9ment tr\u00e8s convoit\u00e9 dans le domaine m\u00e9tallurgique en raison de ses propri\u00e9t\u00e9s exceptionnelles, ce qui contribue \u00e0 sa viabilit\u00e9 en tant que mat\u00e9riau pour les creusets de tantale de haute puret\u00e9. L&#8217;une des caract\u00e9ristiques les plus importantes du tantale est son point de fusion remarquablement \u00e9lev\u00e9, qui se situe \u00e0 environ 3 017 degr\u00e9s Celsius (5 477 degr\u00e9s Fahrenheit). Ce point de fusion \u00e9lev\u00e9 rend les creusets en tantale particuli\u00e8rement adapt\u00e9s aux processus qui impliquent la fusion de m\u00e9taux et d&#8217;autres mat\u00e9riaux \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es. Par exemple, les creusets en tantale pour la fusion sont largement utilis\u00e9s dans diverses applications, allant de l&#8217;a\u00e9rospatiale \u00e0 la fabrication de semi-conducteurs.   <\/p><p>Une autre propri\u00e9t\u00e9 d\u00e9terminante du tantale est sa r\u00e9sistance exceptionnelle \u00e0 la corrosion. Le tantale pr\u00e9sente une inertie remarquable qui lui permet de r\u00e9sister \u00e0 des environnements chimiques agressifs sans se d\u00e9grader. Cette caract\u00e9ristique est particuli\u00e8rement utile dans les laboratoires o\u00f9 des creusets en tantale sans soudure peuvent \u00eatre utilis\u00e9s pour \u00e9viter la contamination pendant les proc\u00e9dures exp\u00e9rimentales critiques. La r\u00e9sistance du mat\u00e9riau \u00e0 un large \u00e9ventail de produits chimiques, y compris l&#8217;acide sulfurique et l&#8217;acide chlorhydrique, souligne encore son importance dans les industries qui d\u00e9pendent du traitement chimique.   <\/p><p>En ce qui concerne la conductivit\u00e9 thermique, la capacit\u00e9 du tantale \u00e0 chauffer efficacement en fait un excellent choix pour les applications n\u00e9cessitant un contr\u00f4le pr\u00e9cis de la temp\u00e9rature. Cette propri\u00e9t\u00e9 est essentielle dans la production de mat\u00e9riaux de haute puret\u00e9, car un chauffage constant garantit l&#8217;uniformit\u00e9 et la qualit\u00e9. C&#8217;est pourquoi les creusets en tantale r\u00e9sistants \u00e0 la corrosion sont souvent utilis\u00e9s dans des applications de haute technologie o\u00f9 la puret\u00e9 des mat\u00e9riaux est primordiale, comme dans la production de composants semi-conducteurs.  <\/p><p>En conclusion, la combinaison unique du tantale avec son point htantalum, son excellente r\u00e9sistance \u00e0 la corrosion et sa conductivit\u00e9 thermique efficace en font un mat\u00e9riau id\u00e9al pour diverses applications de creusets. Qu&#8217;il s&#8217;agisse d&#8217;acheter des creusets en tantale en ligne ou d&#8217;envisager des creusets en tantale sur mesure pour des processus sp\u00e9cialis\u00e9s, il est essentiel de comprendre les propri\u00e9t\u00e9s du tantale pour prendre des d\u00e9cisions \u00e9clair\u00e9es dans le domaine de la m\u00e9tallurgie et au-del\u00e0. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31d5fa6f Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"31d5fa6f\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c3b4cb7 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"5c3b4cb7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-768bf89e elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"768bf89e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 3<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27fc39cb e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"27fc39cb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49c0b580 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"49c0b580\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c9l\u00e9ments \u00e0 prendre en compte pour choisir le bon creuset de tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38d6941c elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"38d6941c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le choix du creuset en tantale appropri\u00e9 peut avoir un impact significatif sur l&#8217;efficacit\u00e9 de vos processus. Un creuset en tantale de haute puret\u00e9 est souvent un choix privil\u00e9gi\u00e9 pour diverses applications en raison de sa remarquable r\u00e9sistance \u00e0 la corrosion et de sa capacit\u00e9 \u00e0 supporter des temp\u00e9ratures extr\u00eames. Lors du choix du creuset appropri\u00e9, plusieurs facteurs doivent \u00eatre pris en compte, notamment la taille, la forme, l&#8217;\u00e9paisseur et les exigences sp\u00e9cifiques de l&#8217;application.  <\/p><p>La taille du creuset en tantale est cruciale car elle doit correspondre au volume de mat\u00e9riau \u00e0 fondre ou \u00e0 traiter. Par exemple, des creusets en tantale plus petits et personnalis\u00e9s peuvent \u00eatre id\u00e9aux pour une utilisation en laboratoire, tandis que des options plus \u00e9tendues conviennent aux applications industrielles. En outre, la forme du creuset peut influencer l&#8217;efficacit\u00e9 du chauffage et la dynamique des fluides de la mati\u00e8re fondue. Pour les proc\u00e9d\u00e9s exigeant de la pr\u00e9cision, un creuset en tantale sans soudure garantit qu&#8217;il n&#8217;y a pas de points faibles susceptibles de compromettre l&#8217;int\u00e9grit\u00e9 du mat\u00e9riau.   <\/p><p>L&#8217;\u00e9paisseur est un autre facteur essentiel \u00e0 prendre en compte lors du choix d&#8217;un creuset en tantale. Un creuset plus \u00e9pais peut offrir une durabilit\u00e9 et une stabilit\u00e9 thermique accrues, ce qui le rend appropri\u00e9 pour les applications \u00e0 haute temp\u00e9rature comme la m\u00e9tallurgie. Inversement, les t\u00e2ches plus d\u00e9licates peuvent b\u00e9n\u00e9ficier d&#8217;options plus fines, car elles chauffent plus rapidement. Comprendre les exigences sp\u00e9cifiques de votre application vous permettra de choisir la bonne \u00e9paisseur.   <\/p><p>La compatibilit\u00e9 avec les mat\u00e9riaux trait\u00e9s est \u00e9galement essentielle. Les creusets \u00e0 faisceau d&#8217;\u00e9lectrons en tantale, par exemple, offrent d&#8217;excellentes performances pour les mat\u00e9riaux qui n\u00e9cessitent un environnement non r\u00e9actif. De plus, opter pour un creuset en tantale pur \u00e0 99,95 % garantit une contamination minimale et offre des conditions de fusion optimales, am\u00e9liorant ainsi la puret\u00e9 du produit final.  <\/p><p>En r\u00e9sum\u00e9, le choix du creuset en tantale appropri\u00e9 n\u00e9cessite une attention particuli\u00e8re \u00e0 la taille, \u00e0 la forme, \u00e0 l&#8217;\u00e9paisseur et \u00e0 la compatibilit\u00e9 des mat\u00e9riaux, afin de garantir des performances et une fiabilit\u00e9 optimales dans diverses applications.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ce2418e external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"2ce2418e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-jpg.webp\" class=\"attachment-full size-full wp-image-48043\" alt=\"crucibles-ma-ebeamsources_std-jpg\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-jpg.webp 600w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-300x300.webp 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-150x150.webp 150w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-100x100.webp 100w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/07\/Crucibles-ma-ebeamsources_std-68x68.webp 68w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fb6305f Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"6fb6305f\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d5c3b25 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"4d5c3b25\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-354379e6 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"354379e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 4<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cb259af e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"3cb259af\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f625545 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"4f625545\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Types de creusets en tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f9dab87 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"4f9dab87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale sont essentiels dans divers processus industriels, en particulier dans la m\u00e9tallurgie et la science des mat\u00e9riaux. Leurs propri\u00e9t\u00e9s uniques, telles qu&#8217;un point de fusion \u00e9lev\u00e9 et une excellente r\u00e9sistance \u00e0 la corrosion, les rendent aptes \u00e0 de multiples applications. Lorsqu&#8217;on \u00e9tudie les creusets en tantale, il est essentiel de noter les distinctions bas\u00e9es sur la forme, la taille et la conception adapt\u00e9es \u00e0 des utilisations sp\u00e9cifiques.  <\/p><p>Les formes les plus courantes des creusets en tantale sont les configurations rondes et carr\u00e9es. Les creusets ronds en tantale sont fr\u00e9quemment utilis\u00e9s en raison de leur distribution uniforme de la chaleur et de leur capacit\u00e9 de fusion efficace, ce qui les rend id\u00e9aux pour les applications de creusets de haute puret\u00e9. D&#8217;autre part, les creusets carr\u00e9s peuvent \u00eatre avantageux pour les applications o\u00f9 une utilisation maximale de l&#8217;espace est essentielle, car ils offrent une plus grande surface pour les mat\u00e9riaux en fusion.  <\/p><p>Les creusets en tantale peuvent avoir des dimensions tr\u00e8s variables et s&#8217;adapter \u00e0 diff\u00e9rentes quantit\u00e9s de m\u00e9tal ou de mat\u00e9riau \u00e0 fondre. Les petites tailles sont souvent pr\u00e9f\u00e9r\u00e9es dans les laboratoires, tandis que les creusets plus grands peuvent \u00eatre n\u00e9cessaires pour les processus industriels. Des options personnalis\u00e9es sont \u00e9galement disponibles, permettant d&#8217;adapter les dimensions aux besoins sp\u00e9cifiques. Les creusets en tantale sur mesure peuvent \u00eatre con\u00e7us aussi bien pour des exp\u00e9riences de laboratoire complexes que pour des processus de fabrication \u00e0 grande \u00e9chelle.   <\/p><p>En outre, des conceptions sp\u00e9cifiques telles que les creusets \u00e0 faisceau d&#8217;\u00e9lectrons en tantale r\u00e9pondent aux d\u00e9fis uniques pos\u00e9s par les applications sp\u00e9cialis\u00e9es. Ces conceptions am\u00e9liorent les performances et la stabilit\u00e9 des creusets lorsqu&#8217;ils sont expos\u00e9s \u00e0 des conditions extr\u00eames. Les creusets en tantale sans soudure utilis\u00e9s en laboratoire garantissent une contamination minimale et augmentent l&#8217;int\u00e9grit\u00e9 des exp\u00e9riences, ce qui est essentiel pour obtenir des r\u00e9sultats d&#8217;une grande puret\u00e9.  <\/p><p>Il est essentiel de comprendre les diff\u00e9rents types de creusets en tantale et leurs applications pour s\u00e9lectionner le creuset adapt\u00e9 \u00e0 vos besoins sp\u00e9cifiques. En examinant attentivement la forme, la taille et les propri\u00e9t\u00e9s des mat\u00e9riaux, les acheteurs peuvent optimiser leurs processus et garantir une efficacit\u00e9 maximale dans des applications allant de la m\u00e9tallurgie \u00e0 la recherche avanc\u00e9e. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53aeb3dd external_elementor-repeater-item-none_external elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-image\" data-id=\"53aeb3dd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/09\/Carousel-ebeam-1-jpg.webp\" class=\"attachment-full size-full wp-image-48387\" alt=\"carousel-ebeam-jpg\" srcset=\"https:\/\/metalstek.com\/wp-content\/uploads\/2024\/09\/Carousel-ebeam-1-jpg.webp 640w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/09\/Carousel-ebeam-1-300x200.webp 300w, https:\/\/metalstek.com\/wp-content\/uploads\/2024\/09\/Carousel-ebeam-1-600x400.webp 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33d71b48 Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"33d71b48\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ffc1c36 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"6ffc1c36\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e951a70 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"1e951a70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 5<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7396b830 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"7396b830\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-465749be elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"465749be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Applications des creusets en tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e82faf elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"26e82faf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale font partie int\u00e9grante de diverses industries en raison de leurs propri\u00e9t\u00e9s uniques, de leurs points de fusion \u00e9lev\u00e9s et de leur r\u00e9sistance exceptionnelle \u00e0 la corrosion. Ces caract\u00e9ristiques les rendent tr\u00e8s efficaces pour la m\u00e9tallurgie, l&#8217;\u00e9lectronique et les applications de traitement chimique. Comprendre les utilisations sp\u00e9cifiques des creusets en tantale permet d&#8217;am\u00e9liorer consid\u00e9rablement l&#8217;efficacit\u00e9 op\u00e9rationnelle dans ces domaines.  <\/p><p>En m\u00e9tallurgie, les creusets en tantale de haute puret\u00e9 sont largement utilis\u00e9s pour fondre et couler des mat\u00e9riaux \u00e0 haute temp\u00e9rature tels que les alliages sp\u00e9ciaux et les m\u00e9taux r\u00e9fractaires. La conception sans soudure de ces creusets leur permet de r\u00e9sister aux conditions extr\u00eames rencontr\u00e9es au cours des processus de fusion. Les creusets en tantale Ta sont notamment privil\u00e9gi\u00e9s pour la production de mat\u00e9riaux de haute performance n\u00e9cessitant une int\u00e9grit\u00e9 structurelle exceptionnelle, ce qui les rend essentiels dans les industries a\u00e9rospatiale et automobile.  <\/p><p>Dans le domaine de l&#8217;\u00e9lectronique, les creusets en tantale jouent un r\u00f4le essentiel dans la production de condensateurs et d&#8217;autres composants \u00e9lectroniques. Leur capacit\u00e9 \u00e0 supporter des temp\u00e9ratures \u00e9lev\u00e9es et \u00e0 r\u00e9sister \u00e0 l&#8217;oxydation est cruciale lorsqu&#8217;il s&#8217;agit de mat\u00e9riaux n\u00e9cessitant une gestion thermique pr\u00e9cise. En particulier, les creusets en tantale pour faisceau d&#8217;\u00e9lectrons sont utilis\u00e9s dans les processus d&#8217;\u00e9vaporation par faisceau d&#8217;\u00e9lectrons, essentiels pour le d\u00e9p\u00f4t de couches minces dans la fabrication des semi-conducteurs.  <\/p><p>Le traitement chimique b\u00e9n\u00e9ficie \u00e9galement de l&#8217;utilisation de creusets en tantale r\u00e9sistants \u00e0 la corrosion. Ces creusets sont id\u00e9aux pour manipuler des produits chimiques agressifs et des environnements r\u00e9actifs, offrant s\u00e9curit\u00e9 et long\u00e9vit\u00e9 dans diverses r\u00e9actions chimiques. Les industries qui exigent pr\u00e9cision et fiabilit\u00e9 dans le traitement chimique, telles que les industries pharmaceutiques et p\u00e9trochimiques, s&#8217;appuient sur des creusets en tantale sur mesure qui peuvent \u00eatre adapt\u00e9s pour r\u00e9pondre \u00e0 des exigences sp\u00e9cifiques.  <\/p><p>Dans l&#8217;ensemble, les creusets en tantale sont essentiels dans de nombreux secteurs, fournissant des solutions qui am\u00e9liorent la qualit\u00e9 des produits et l&#8217;efficacit\u00e9 op\u00e9rationnelle. Leur polyvalence et leur r\u00e9silience en font l&#8217;un des premiers choix pour les fabricants qui cherchent \u00e0 optimiser leurs processus et leurs r\u00e9sultats. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ef977fe Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"7ef977fe\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7aa9b54f elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"7aa9b54f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49e2627e elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"49e2627e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 7<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71d39965 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"71d39965\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ce6cbd elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"12ce6cbd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Malentendus courants sur les creusets en tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-765c57c0 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"765c57c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il existe plusieurs id\u00e9es fausses sur les creusets en tantale qui peuvent pr\u00eater \u00e0 confusion quant \u00e0 leur utilisation et leur fiabilit\u00e9. L&#8217;un des mythes les plus r\u00e9pandus est que les creusets en tantale sont trop fragiles et ne peuvent pas r\u00e9sister \u00e0 des environnements \u00e0 haute temp\u00e9rature. En r\u00e9alit\u00e9, le tantale poss\u00e8de un point de fusion exceptionnellement \u00e9lev\u00e9, d&#8217;environ 3 017\u00b0C (5 467\u00b0F), ce qui rend les creusets en tantale bien adapt\u00e9s aux applications en m\u00e9tallurgie, en particulier pour la fusion de nombreux m\u00e9taux et compos\u00e9s. Cette durabilit\u00e9 est l&#8217;une des principales raisons pour lesquelles de nombreuses industries utilisent des creusets en tantale de haute puret\u00e9 pour des processus critiques.   <\/p><p>Un autre malentendu concerne la perception de la limitation des creusets en tantale \u00e0 des applications sp\u00e9cifiques. S&#8217;il est vrai que ces creusets sont souvent utilis\u00e9s dans des environnements de haute technologie, comme la fabrication de semi-conducteurs et les fours \u00e0 vide, la polyvalence des creusets en tantale sur mesure leur permet de s&#8217;adapter \u00e0 diverses utilisations. Des laboratoires de recherche aux environnements industriels, ils sont utilis\u00e9s dans des processus exigeant des niveaux \u00e9lev\u00e9s de puret\u00e9 et de r\u00e9sistance \u00e0 la corrosion, ce qui \u00e9largit leur champ d&#8217;application au-del\u00e0 de ce que l&#8217;on pourrait imaginer.  <\/p><p>Certaines personnes pensent \u00e9galement que les creusets en tantale ne sont pas rentables en raison de l&#8217;investissement initial plus \u00e9lev\u00e9 que les mat\u00e9riaux traditionnels. Cependant, les avantages \u00e0 long terme offerts par un creuset en tantale pur \u00e0 99,95 %, tels que la r\u00e9duction des risques de contamination et la prolongation de la dur\u00e9e de vie, peuvent se traduire par des \u00e9conomies globales. En outre, la conception sans soudure des creusets \u00e0 faisceaux d&#8217;\u00e9lectrons en tantale minimise les risques de faiblesses structurelles, ce qui am\u00e9liore leurs performances dans les environnements intenses.  <\/p><p>Enfin, bien que l&#8217;on puisse penser que ces creusets ne sont pas faciles \u00e0 trouver, il est d\u00e9sormais pratique d&#8217;acheter des creusets en tantale en ligne, ce qui les rend accessibles \u00e0 un plus grand nombre d&#8217;utilisateurs. Comprendre ces aspects permet de dissiper les mythes qui entourent les creusets en tantale et de mettre en \u00e9vidence leurs avantages dans diverses applications. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fc898d Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"6fc898d\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0efe994 elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"0efe994\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1da448f elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"1da448f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 8<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f204dfc e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"f204dfc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84fab0d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"84fab0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Creuset de tantale Questions fr\u00e9quemment pos\u00e9es (FAQ)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f406070 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"f406070\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale sont essentiels dans diverses applications scientifiques et industrielles en raison de leurs propri\u00e9t\u00e9s exceptionnelles. Nous r\u00e9pondons ici \u00e0 quelques questions courantes concernant l&#8217;entretien, la long\u00e9vit\u00e9, la compatibilit\u00e9 et le d\u00e9pannage des creusets en tantale. <\/p><p><strong>Quelle est la dur\u00e9e de vie d&#8217;un creuset en tantale de haute puret\u00e9 ?<\/strong><br>La long\u00e9vit\u00e9 d&#8217;un creuset en tantale d\u00e9pend largement de ses conditions d&#8217;utilisation, notamment de la temp\u00e9rature et des substances avec lesquelles il entre en contact. Un creuset de fusion en tantale bien entretenu peut durer plusieurs ann\u00e9es, principalement lorsqu&#8217;il est utilis\u00e9 dans les limites de temp\u00e9rature recommand\u00e9es et dans des environnements appropri\u00e9s. <\/p><p><strong>Comment dois-je entretenir mes creusets en tantale sans soudure pour une utilisation en laboratoire ?<\/strong><br>Pour prolonger la dur\u00e9e de vie de vos creusets en tantale r\u00e9sistants \u00e0 la corrosion, il est essentiel de suivre des protocoles d&#8217;entretien appropri\u00e9s. Il s&#8217;agit notamment de nettoyer apr\u00e8s chaque utilisation, d&#8217;\u00e9viter les changements brusques de temp\u00e9rature et de veiller \u00e0 ce que le creuset soit exempt de contaminants susceptibles d&#8217;entra\u00eener une d\u00e9gradation du mat\u00e9riau. <\/p><p><strong>Un creuset en tantale sur mesure est-il compatible avec toutes les substances ?<\/strong><br>Bien que le tantale soit connu pour sa compatibilit\u00e9 avec divers mat\u00e9riaux, il n&#8217;est pas universellement compatible. Il est particuli\u00e8rement r\u00e9sistant \u00e0 la corrosion acide mais peut r\u00e9agir de mani\u00e8re d\u00e9favorable avec certains alcalis et environnements \u00e0 haute temp\u00e9rature. Les utilisateurs doivent se r\u00e9f\u00e9rer aux fiches de donn\u00e9es de s\u00e9curit\u00e9 pour v\u00e9rifier la compatibilit\u00e9.  <\/p><p><strong>Quels sont les probl\u00e8mes courants rencontr\u00e9s avec les creusets \u00e0 faisceau d&#8217;\u00e9lectrons en tantale ?<\/strong><br>Les probl\u00e8mes les plus courants sont l&#8217;usure pr\u00e9matur\u00e9e, les fissures ou les d\u00e9formations dues \u00e0 une mauvaise manipulation ou \u00e0 des chocs thermiques extr\u00eames. Des inspections r\u00e9guli\u00e8res et des pratiques d&#8217;utilisation appropri\u00e9es sont essentielles pour att\u00e9nuer ces probl\u00e8mes potentiels. <\/p><p>Pour de plus amples informations ou pour acheter des creusets en tantale en ligne, il est conseill\u00e9 de consulter des fournisseurs r\u00e9put\u00e9s qui peuvent fournir des sp\u00e9cifications d\u00e9taill\u00e9es et des recommandations adapt\u00e9es \u00e0 vos besoins sp\u00e9cifiques.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23048e55 Chapter e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"23048e55\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e20ff6a elementor-repeater-item-none elementor-repeater-item-none_hover e-flex e-con-boxed elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"3e20ff6a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cabf606 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"4cabf606\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chapitre 9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36680edd e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-transform e-flex elementor-repeater-item-default_padding sk-none e-con e-child\" data-id=\"36680edd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-35,&quot;sizes&quot;:[]},&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-493ff49d elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"493ff49d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MetalsTek : Votre partenaire de confiance pour les creusets en tantale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2039f5b5 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"2039f5b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les creusets en tantale jouent un r\u00f4le essentiel dans diverses applications industrielles en raison de leurs propri\u00e9t\u00e9s remarquables, en particulier les creusets en tantale de haute puret\u00e9 recherch\u00e9s dans les secteurs de la m\u00e9tallurgie et de l&#8217;\u00e9lectronique. Les caract\u00e9ristiques uniques du tantale, telles que son point de fusion \u00e9lev\u00e9 et sa r\u00e9sistance exceptionnelle \u00e0 la corrosion, font des creusets en tantale un choix id\u00e9al pour la fusion et le traitement des mat\u00e9riaux \u00e0 haute temp\u00e9rature. Les utilisateurs peuvent acheter des creusets en tantale en ligne, ce qui leur permet d&#8217;avoir acc\u00e8s \u00e0 des creusets en tantale sans soudure pour une utilisation en laboratoire et \u00e0 des creusets en tantale sur mesure adapt\u00e9s \u00e0 des exigences sp\u00e9cifiques.  <\/p><p>La demande de pr\u00e9cision dans la fabrication et le traitement augmentant, l&#8217;application des creusets \u00e0 faisceau d&#8217;\u00e9lectrons en tantale devient de plus en plus courante. Ces creusets offrent une stabilit\u00e9 thermique accrue et des niveaux de puret\u00e9 allant jusqu&#8217;\u00e0 99,95 % pour des r\u00e9sultats de haute qualit\u00e9 dans la synth\u00e8se de mat\u00e9riaux avanc\u00e9s. L&#8217;utilisation du tantale dans les creusets pour les op\u00e9rations de fusion devrait se d\u00e9velopper \u00e0 mesure que les industries s&#8217;efforcent d&#8217;atteindre des normes de performance plus \u00e9lev\u00e9es et de r\u00e9duire la contamination dans leurs processus.  <\/p><p>Outre les applications actuelles, les tendances futures dans le domaine de la science des mat\u00e9riaux peuvent influencer de mani\u00e8re significative le d\u00e9veloppement et l&#8217;utilisation des creusets en tantale. Avec les progr\u00e8s technologiques, nous pr\u00e9voyons des am\u00e9liorations dans les techniques de fabrication qui pourraient conduire \u00e0 des niveaux de puret\u00e9 encore plus \u00e9lev\u00e9s et \u00e0 des options personnalis\u00e9es. Les recherches en cours sur l&#8217;alliage des m\u00e9taux et les mat\u00e9riaux composites pourraient \u00e9galement ouvrir de nouvelles voies pour combiner le tantale avec d&#8217;autres \u00e9l\u00e9ments, ce qui permettrait d&#8217;obtenir des propri\u00e9t\u00e9s am\u00e9lior\u00e9es pour des applications sp\u00e9cialis\u00e9es.  <\/p><p>L&#8217;importance croissante accord\u00e9e \u00e0 la durabilit\u00e9 et \u00e0 l&#8217;utilisation efficace des ressources dans les processus de fabrication va probablement stimuler la croissance des creusets en tantale r\u00e9sistants \u00e0 la corrosion. Comme les industries recherchent des alternatives respectueuses de l&#8217;environnement, les propri\u00e9t\u00e9s uniques du tantale deviendront de plus en plus pr\u00e9cieuses. L&#8217;avenir est prometteur pour les creusets en tantale, car leur importance dans la m\u00e9tallurgie et les domaines connexes continue de s&#8217;\u00e9tendre.  <\/p><p>Chez MetalsTek, nous sommes tr\u00e8s fiers de fournir des creusets en tantale de premi\u00e8re qualit\u00e9 qui r\u00e9pondent aux exigences des industries d&#8217;aujourd&#8217;hui. Notre attachement \u00e0 la qualit\u00e9 et notre capacit\u00e9 \u00e0 adapter les cibles \u00e0 des tailles et compositions pr\u00e9cises font de nous le choix privil\u00e9gi\u00e9 des entreprises qui cherchent \u00e0 repousser les limites et \u00e0 atteindre l&#8217;excellence. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-606a95c e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"606a95c\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac7cc6 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-template\" data-id=\"7ac7cc6\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"58639\" class=\"elementor elementor-58639 elementor-32437\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-482cc71e e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"482cc71e\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-740e2f91 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-heading\" data-id=\"740e2f91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Produit connexe<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17228487 e-flex e-con-boxed elementor-repeater-item-default_padding elementor-repeater-item-none elementor-repeater-item-none_hover e-con e-child\" data-id=\"17228487\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dfdb1fc e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"dfdb1fc\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21d28609 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"21d28609\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/tungstene-w\/creusets-en-tungstene\/\">Creuset en tungst\u00e8ne<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/molybdene-mo\/creuset-de-molybdene\/\">Creuset de molybd\u00e8ne et bateau<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/tantale-ta\/creuset-de-tantale\/\">Creuset de tantale<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/niobiumnb\/coupe-a-creuset-en-niobium\/\">Creuset de Niobium<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/zirconiumzr\/mortier-pilon-et-creuset-en-zircone\/\">Mortier, pilon et creuset en zircone<\/a><\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-694eb282 e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"694eb282\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d3bda89 elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"1d3bda89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-rares\/iridiumir\/creuset-diridium\/\">Creuset d&#8217;iridium<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-rares\/platine-pt\/creusets-en-platine\/\">Creusets en platine<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-refractaires\/rhenium-re\/creuset-de-rhenium\/\">Creuset de rh\u00e9nium<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/metaux-de-base\/nickelni\/creuset-de-nickel\/\">Creuset de nickel<\/a><\/li>    <li><a href=\"https:\/\/metalstek.com\/fr\/materiaux-de-depot\/creusets-et-barques\/creusets-en-oxyde-daluminium-pour-sources-a-faisceau-delectrons\/\">Creusets en oxyde d&#8217;aluminium pour sources \u00e0 faisceau d&#8217;\u00e9lectrons<\/a><\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-192b1feb e-con-full elementor-repeater-item-none elementor-repeater-item-none_hover e-flex elementor-repeater-item-default_padding e-con e-child\" data-id=\"192b1feb\" data-element_type=\"container\" data-settings=\"{&quot;ang_container_spacing_size&quot;:&quot;default_padding&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60c8346b elementor-repeater-item-none elementor-repeater-item-none_hover elementor-widget elementor-widget-text-editor\" data-id=\"60c8346b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n\n    <li><a href=\"https:\/\/metalstek.com\/fr\/materiaux-de-depot\/creusets-et-barques\/creusets-a-faisceau-delectrons-en-nitrure-de-bore\/\">Creusets \u00e0 faisceau d&#8217;\u00e9lectrons en nitrure de bore<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/graphite-e-beam-crucibles\/\">Creusets E-Beam en graphite<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fabmate-e-beam-crucibles\/\">Creusets FABMATE\u00ae \u00e0 poutre en E<\/a><\/li>\n    <li><a href=\"https:\/\/metalstek.com\/fr\/materiaux-de-depot\/creusets-et-barques\/creusets-intermetalliques-bn-tib2-e-beam\/\">Creusets interm\u00e9talliques (BN-TiB2) E-Beam<\/a><\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Creusets en tantale pour applications \u00e0 haute temp\u00e9rature Creuset pour faisceau d&#8217;\u00e9lectrons en tantale Mat\u00e9riau : Tantale ou alliages de tantale Grade : R05200, R05400, R05252 (Ta-2.5W), R05255 (Ta-10W), R05240 (Ta-40Nb) Puret\u00e9 : &gt;99,9% Norme : ASTM B708 Surface : Polie, Finition Tournage Obtenir un devis Creuset standard en tantale (cylindrique) Mat\u00e9riau : Tantale ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":50554,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Commander des creusets de tantale \u00e0 des prix comp\u00e9titifs | MetalsTek","_seopress_titles_desc":"MetalsTek propose des creusets en tantale de premi\u00e8re qualit\u00e9 pour les applications \u00e0 haute temp\u00e9rature. Des tailles personnalis\u00e9es sont disponibles. Demandez un devis pour des solutions fiables et durables.  ","_seopress_robots_index":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"_links":{"self":[{"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/pages\/54675"}],"collection":[{"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/comments?post=54675"}],"version-history":[{"count":2,"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/pages\/54675\/revisions"}],"predecessor-version":[{"id":54681,"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/pages\/54675\/revisions\/54681"}],"up":[{"embeddable":true,"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/pages\/50554"}],"wp:attachment":[{"href":"https:\/\/metalstek.com\/fr\/wp-json\/wp\/v2\/media?parent=54675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}